{"id":13675,"date":"2015-07-29T00:00:00","date_gmt":"2015-07-29T03:00:00","guid":{"rendered":"https:\/\/alehlatam.org\/wp2024\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/"},"modified":"2015-07-29T00:00:00","modified_gmt":"2015-07-29T03:00:00","slug":"ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica","status":"publish","type":"post","link":"https:\/\/alehlatam.org\/en\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/","title":{"rendered":"II PARTE HEPATOLOG\u00cdA De las Ciencias B\u00e1sicas a las Cl\u00ednicas, de los Problemas a los S\u00edndromes, de la Docencia a la Pr\u00e1ctica M\u00e9dica."},"content":{"rendered":"<p>Editores: Drs. Juan J. Su\u00e1rez Mart\u00ednez y Miquel Bruguera Cortada.<\/p>\n<p>Tenemos el agrado de comunicarles que se encuentra disponible en la p\u00e1gina web de ALEH la 2\u00aa Parte de este Libro.\u00a0 En esta secci\u00f3n se abordan de forma muy completa\u00a0 y did\u00e1ctica\u00a0 las enfermedades hepatobiliares, revis\u00e1ndose los factores de riesgo, la semiolog\u00eda, laboratorio, imagenolog\u00eda, endoscop\u00eda y anatom\u00eda patol\u00f3gica. Todo ejemplificado con casos cl\u00ednicos y acompa\u00f1ado de algoritmos diagn\u00f3sticos e im\u00e1genes. Por todo lo anterior recomendamos continuar con la lectura de este interesante texto.<\/p>\n<ul>\n<li class=\"lastItem firstItem\"><a href=\"http:\/\/www.alehlatam.org\/documentos\/H_II_90_a_295.pdf\" target=\"_blank\" rel=\"noopener\">Descargar Parte II Ciencias Cl\u00ednicas Cap. 1 -2<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Editores: Drs. Juan J. Su\u00e1rez Mart\u00ednez y Miquel Bruguera Cortada. Tenemos el agrado de comunicarles que se encuentra disponible en la p\u00e1gina web de ALEH la 2\u00aa Parte de este Libro.\u00a0 En esta secci\u00f3n se abordan de forma muy completa\u00a0 y did\u00e1ctica\u00a0 las enfermedades hepatobiliares, revis\u00e1ndose los factores de riesgo, la semiolog\u00eda, laboratorio, imagenolog\u00eda, endoscop\u00eda [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13675","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>II PARTE HEPATOLOG\u00cdA De las Ciencias B\u00e1sicas a las Cl\u00ednicas, de los Problemas a los S\u00edndromes, de la Docencia a la Pr\u00e1ctica M\u00e9dica. - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alehlatam.org\/en\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"II PARTE HEPATOLOG\u00cdA De las Ciencias B\u00e1sicas a las Cl\u00ednicas, de los Problemas a los S\u00edndromes, de la Docencia a la Pr\u00e1ctica M\u00e9dica. - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"og:description\" content=\"Editores: Drs. Juan J. Su\u00e1rez Mart\u00ednez y Miquel Bruguera Cortada. Tenemos el agrado de comunicarles que se encuentra disponible en la p\u00e1gina web de ALEH la 2\u00aa Parte de este Libro.\u00a0 En esta secci\u00f3n se abordan de forma muy completa\u00a0 y did\u00e1ctica\u00a0 las enfermedades hepatobiliares, revis\u00e1ndose los factores de riesgo, la semiolog\u00eda, laboratorio, imagenolog\u00eda, endoscop\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alehlatam.org\/en\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/\" \/>\n<meta property=\"og:site_name\" content=\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-29T03:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alehlatam.org\/wp-content\/uploads\/2026\/01\/Default-banner-para-links-externos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\"},\"headline\":\"II PARTE HEPATOLOG\u00cdA De las Ciencias B\u00e1sicas a las Cl\u00ednicas, de los Problemas a los S\u00edndromes, de la Docencia a la Pr\u00e1ctica M\u00e9dica.\",\"datePublished\":\"2015-07-29T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\\\/\"},\"wordCount\":134,\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\\\/\",\"name\":\"II PARTE HEPATOLOG\u00cdA De las Ciencias B\u00e1sicas a las Cl\u00ednicas, de los Problemas a los S\u00edndromes, de la Docencia a la Pr\u00e1ctica M\u00e9dica. - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\"},\"datePublished\":\"2015-07-29T03:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alehlatam.org\\\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/alehlatam.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"II PARTE HEPATOLOG\u00cdA De las Ciencias B\u00e1sicas a las Cl\u00ednicas, de los Problemas a los S\u00edndromes, de la Docencia a la Pr\u00e1ctica M\u00e9dica.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"name\":\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"description\":\"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.\",\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"alternateName\":\"ALEH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alehlatam.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\",\"name\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"alternateName\":\"ALEH\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"width\":2000,\"height\":1493,\"caption\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/alehlatam.org\"],\"url\":\"https:\\\/\\\/alehlatam.org\\\/en\\\/author\\\/admin-eventual\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"II PARTE HEPATOLOG\u00cdA De las Ciencias B\u00e1sicas a las Cl\u00ednicas, de los Problemas a los S\u00edndromes, de la Docencia a la Pr\u00e1ctica M\u00e9dica. - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alehlatam.org\/en\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/","og_locale":"en_US","og_type":"article","og_title":"II PARTE HEPATOLOG\u00cdA De las Ciencias B\u00e1sicas a las Cl\u00ednicas, de los Problemas a los S\u00edndromes, de la Docencia a la Pr\u00e1ctica M\u00e9dica. - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","og_description":"Editores: Drs. Juan J. Su\u00e1rez Mart\u00ednez y Miquel Bruguera Cortada. Tenemos el agrado de comunicarles que se encuentra disponible en la p\u00e1gina web de ALEH la 2\u00aa Parte de este Libro.\u00a0 En esta secci\u00f3n se abordan de forma muy completa\u00a0 y did\u00e1ctica\u00a0 las enfermedades hepatobiliares, revis\u00e1ndose los factores de riesgo, la semiolog\u00eda, laboratorio, imagenolog\u00eda, endoscop\u00eda [&hellip;]","og_url":"https:\/\/alehlatam.org\/en\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/","og_site_name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","article_published_time":"2015-07-29T03:00:00+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2026\/01\/Default-banner-para-links-externos.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alehlatam.org\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/#article","isPartOf":{"@id":"https:\/\/alehlatam.org\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/"},"author":{"name":"admin","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f"},"headline":"II PARTE HEPATOLOG\u00cdA De las Ciencias B\u00e1sicas a las Cl\u00ednicas, de los Problemas a los S\u00edndromes, de la Docencia a la Pr\u00e1ctica M\u00e9dica.","datePublished":"2015-07-29T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/alehlatam.org\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/"},"wordCount":134,"publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/alehlatam.org\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/","url":"https:\/\/alehlatam.org\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/","name":"II PARTE HEPATOLOG\u00cdA De las Ciencias B\u00e1sicas a las Cl\u00ednicas, de los Problemas a los S\u00edndromes, de la Docencia a la Pr\u00e1ctica M\u00e9dica. - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","isPartOf":{"@id":"https:\/\/alehlatam.org\/#website"},"datePublished":"2015-07-29T03:00:00+00:00","breadcrumb":{"@id":"https:\/\/alehlatam.org\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alehlatam.org\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alehlatam.org\/ii-parte-hepatologia-de-las-ciencias-basicas-a-las-clinicas-de-los-problemas-a-los-sindromes-de-la-docencia-a-la-practica-medica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/alehlatam.org\/"},{"@type":"ListItem","position":2,"name":"II PARTE HEPATOLOG\u00cdA De las Ciencias B\u00e1sicas a las Cl\u00ednicas, de los Problemas a los S\u00edndromes, de la Docencia a la Pr\u00e1ctica M\u00e9dica."}]},{"@type":"WebSite","@id":"https:\/\/alehlatam.org\/#website","url":"https:\/\/alehlatam.org\/","name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","description":"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.","publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"alternateName":"ALEH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alehlatam.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/alehlatam.org\/#organization","name":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","alternateName":"ALEH","url":"https:\/\/alehlatam.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","width":2000,"height":1493,"caption":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado"},"image":{"@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/alehlatam.org"],"url":"https:\/\/alehlatam.org\/en\/author\/admin-eventual\/"}]}},"_links":{"self":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/posts\/13675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/comments?post=13675"}],"version-history":[{"count":0,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/posts\/13675\/revisions"}],"wp:attachment":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/media?parent=13675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/categories?post=13675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/tags?post=13675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}