{"id":13879,"date":"2016-12-21T00:00:00","date_gmt":"2016-12-21T03:00:00","guid":{"rendered":"https:\/\/alehlatam.org\/wp2024\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/"},"modified":"2016-12-21T00:00:00","modified_gmt":"2016-12-21T03:00:00","slug":"nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2","status":"publish","type":"post","link":"https:\/\/alehlatam.org\/en\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/","title":{"rendered":"Nuevos avances y desaf\u00edos del Grupo de Inter\u00e9s Hepatotoxicidad &#8211; ALEH"},"content":{"rendered":"<p>Estimados amigos de ALEH:<\/p>\n<p>Hace ya 5 a\u00f1os que estamos construyendo el Registro Latinoamericano de Hepatotoxicidad (LATINDILI) y consideramos importante que conozcan nuestros logros y como sumarse a este proyecto.<br \/>\nComo podr\u00e1n ver en el <a href=\"http:\/\/alehlatam.org\/en\/investigacion-y-educacion\/guias-latinoamericanas\/\" target=\"_blank\" rel=\"noopener\">siguiente presentaci\u00f3n<\/a>, el cual fue recientemente presentado en Chile, les enviamos un resumen de toda nuestra trayectoria en forma actualizada y amena.<\/p>\n<p>Alli ver\u00e1n como es el formulario para cargar los casos, ademas de todos nuestros logros y por cierto, tambien nuestras dificultades y futuros desafios. Encontrar\u00e1n tambien, el sitio web de LATINDILI y las direcciones de correo para contactarse y as\u00ed poder ser incluidos en nuestro registro como participantes activos.<\/p>\n<p>Gracias al apoyo incondicional del registro Espa\u00f1ol de Hepatotoxicidad coordinado por Ra\u00fal Andrade y Maribel Lucena pudimos construir los pilares de esta red que hoy cuenta con la participaci\u00f3n de varios paises en Latinoamerica. Sin embargo, algunos paises no se han unido todav\u00eda al proyecto y otros, por diferentes razones, a\u00fan no pudieron contribuir con el apropiado n\u00famero de casos.<\/p>\n<p>El registro LATINDILI tiene planeado llegar a 300 casos a corto plazo (hoy cuenta con 260), y de esa forma poder llegar a mostrar nuestros resultados al mundo y poder compararnos con los otros registros internacionales. Para que esto ocurra, necesitamos del esfuerzo mancomunado de todos nosotros.<\/p>\n<p>Queremos contarles con alegr\u00eda que estamos programado reuniones online de discusi\u00f3n de casos problemas generados por f\u00e1rmacos, los cuales ser\u00e1n coordinados por nuestro equipo y que tendr\u00e1n una frecuencia semanal. El Dr Raymundo Paran\u00e1 de Salvador de Bahia y Marco Arrese se acaban de agregar al grupo coordinador de estas reuniones interactivas. En breve ser\u00e1n informados sobre cual es el sitio web donde podr\u00e1n encontrar un link para acceder en forma masiva y gratuita.<\/p>\n<p>Nuestro objetivo m\u00e1s importante, adem\u00e1s de conocer el comportamimeto de la toxicidad hep\u00e1tica en LA, es llegar a tener una maquinaria muy entrenada de comunicaci\u00f3n entre nuestros paises y que pueda ser \u00fatil para incluir y desarrollar otros proyectos multic\u00e9ntricos<\/p>\n<p>Gracias al comprometido apoyo de Fernando Contreras como presidente de ALEH y a la valiosa e incansable ayuda de Nelia Hernandez, seguramente podremos llegar a buen puerto. Todos nosotros estamos muy atentos a cualquier iniciativa o sugerencia de ustedes con el \u00fanico fin de seguir construyendo juntos&#8230; no duden en contactarnos!<\/p>\n<p>Un fuerte abrazo para todo,<\/p>\n<p>DR. FERNANDO BESSONE<br \/>\nARGENTINA<\/p>\n<p><a href=\"http:\/\/alehlatam.org\/en\/investigacion-y-educacion\/guias-latinoamericanas\/\" target=\"_blank\" rel=\"noopener\"><strong>Ver Presentaci\u00f3n<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Estimados amigos de ALEH: Hace ya 5 a\u00f1os que estamos construyendo el Registro Latinoamericano de Hepatotoxicidad (LATINDILI) y consideramos importante que conozcan nuestros logros y como sumarse a este proyecto. Como podr\u00e1n ver en el siguiente presentaci\u00f3n, el cual fue recientemente presentado en Chile, les enviamos un resumen de toda nuestra trayectoria en forma actualizada [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13879","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevos avances y desaf\u00edos del Grupo de Inter\u00e9s Hepatotoxicidad - ALEH - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alehlatam.org\/en\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevos avances y desaf\u00edos del Grupo de Inter\u00e9s Hepatotoxicidad - ALEH - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"og:description\" content=\"Estimados amigos de ALEH: Hace ya 5 a\u00f1os que estamos construyendo el Registro Latinoamericano de Hepatotoxicidad (LATINDILI) y consideramos importante que conozcan nuestros logros y como sumarse a este proyecto. Como podr\u00e1n ver en el siguiente presentaci\u00f3n, el cual fue recientemente presentado en Chile, les enviamos un resumen de toda nuestra trayectoria en forma actualizada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alehlatam.org\/en\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/\" \/>\n<meta property=\"og:site_name\" content=\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-21T03:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alehlatam.org\/wp-content\/uploads\/2026\/01\/Default-banner-para-links-externos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\"},\"headline\":\"Nuevos avances y desaf\u00edos del Grupo de Inter\u00e9s Hepatotoxicidad &#8211; ALEH\",\"datePublished\":\"2016-12-21T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\\\/\"},\"wordCount\":423,\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\\\/\",\"name\":\"Nuevos avances y desaf\u00edos del Grupo de Inter\u00e9s Hepatotoxicidad - ALEH - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\"},\"datePublished\":\"2016-12-21T03:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alehlatam.org\\\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/alehlatam.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuevos avances y desaf\u00edos del Grupo de Inter\u00e9s Hepatotoxicidad &#8211; ALEH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"name\":\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"description\":\"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.\",\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"alternateName\":\"ALEH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alehlatam.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\",\"name\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"alternateName\":\"ALEH\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"width\":2000,\"height\":1493,\"caption\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/alehlatam.org\"],\"url\":\"https:\\\/\\\/alehlatam.org\\\/en\\\/author\\\/admin-eventual\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevos avances y desaf\u00edos del Grupo de Inter\u00e9s Hepatotoxicidad - ALEH - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alehlatam.org\/en\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/","og_locale":"en_US","og_type":"article","og_title":"Nuevos avances y desaf\u00edos del Grupo de Inter\u00e9s Hepatotoxicidad - ALEH - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","og_description":"Estimados amigos de ALEH: Hace ya 5 a\u00f1os que estamos construyendo el Registro Latinoamericano de Hepatotoxicidad (LATINDILI) y consideramos importante que conozcan nuestros logros y como sumarse a este proyecto. Como podr\u00e1n ver en el siguiente presentaci\u00f3n, el cual fue recientemente presentado en Chile, les enviamos un resumen de toda nuestra trayectoria en forma actualizada [&hellip;]","og_url":"https:\/\/alehlatam.org\/en\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/","og_site_name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","article_published_time":"2016-12-21T03:00:00+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2026\/01\/Default-banner-para-links-externos.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alehlatam.org\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/#article","isPartOf":{"@id":"https:\/\/alehlatam.org\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/"},"author":{"name":"admin","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f"},"headline":"Nuevos avances y desaf\u00edos del Grupo de Inter\u00e9s Hepatotoxicidad &#8211; ALEH","datePublished":"2016-12-21T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/alehlatam.org\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/"},"wordCount":423,"publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/alehlatam.org\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/","url":"https:\/\/alehlatam.org\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/","name":"Nuevos avances y desaf\u00edos del Grupo de Inter\u00e9s Hepatotoxicidad - ALEH - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","isPartOf":{"@id":"https:\/\/alehlatam.org\/#website"},"datePublished":"2016-12-21T03:00:00+00:00","breadcrumb":{"@id":"https:\/\/alehlatam.org\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alehlatam.org\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alehlatam.org\/nuevos-avances-y-desafios-del-grupo-de-interes-hepatotoxicidad-aleh-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/alehlatam.org\/"},{"@type":"ListItem","position":2,"name":"Nuevos avances y desaf\u00edos del Grupo de Inter\u00e9s Hepatotoxicidad &#8211; ALEH"}]},{"@type":"WebSite","@id":"https:\/\/alehlatam.org\/#website","url":"https:\/\/alehlatam.org\/","name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","description":"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.","publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"alternateName":"ALEH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alehlatam.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/alehlatam.org\/#organization","name":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","alternateName":"ALEH","url":"https:\/\/alehlatam.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","width":2000,"height":1493,"caption":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado"},"image":{"@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/alehlatam.org"],"url":"https:\/\/alehlatam.org\/en\/author\/admin-eventual\/"}]}},"_links":{"self":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/posts\/13879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/comments?post=13879"}],"version-history":[{"count":0,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/posts\/13879\/revisions"}],"wp:attachment":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/media?parent=13879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/categories?post=13879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/tags?post=13879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}