{"id":13898,"date":"2016-07-21T00:00:00","date_gmt":"2016-07-21T04:00:00","guid":{"rendered":"https:\/\/alehlatam.org\/wp2024\/simposio-internacional-de-hepatologia-2016-3\/"},"modified":"2016-07-21T00:00:00","modified_gmt":"2016-07-21T04:00:00","slug":"simposio-internacional-de-hepatologia-2016-3","status":"publish","type":"post","link":"https:\/\/alehlatam.org\/en\/simposio-internacional-de-hepatologia-2016-3\/","title":{"rendered":"Simposio Internacional de Hepatolog\u00eda 2016"},"content":{"rendered":"<p><strong>Nuevos Horizontes Terap\u00e9uticos en Hepatolog\u00eda. Buenos Aires Argentina.<\/strong><\/p>\n<p>Con gran \u00e9xito y numerosa asistencia se realiz\u00f3, del 22 al 24 de junio, en Buenos Aires Argentina, el Simposio Internacional de Hepatolog\u00eda, \u201cNuevos Horizontes Terap\u00e9uticos en Hepatolog\u00eda\u201d. El comit\u00e9 organizador tuvo al Dr. Adri\u00e1n Gadano como presidente y al Dr. Ezequiel Ridruejo como vicepresidente. Como invitados extranjeros cont\u00f3 con la presencia del Dr. Jos\u00e9 Luis Calleja (Espa\u00f1a), Dr. Hugo Cheinquer (Brasil), Dr. Francois Durand (Francia), Dr, Jordan J. Feld (Canada) y la Dra. Claudia Oliveira (Brasil). Las conferencias abordaron temas relacionados a hepatitis virales, enfermedades metab\u00f3licas, autoinmunidad, NASH y varios t\u00f3picos sobre cirrosis y sus complicaciones.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nuevos Horizontes Terap\u00e9uticos en Hepatolog\u00eda. Buenos Aires Argentina. Con gran \u00e9xito y numerosa asistencia se realiz\u00f3, del 22 al 24 de junio, en Buenos Aires Argentina, el Simposio Internacional de Hepatolog\u00eda, \u201cNuevos Horizontes Terap\u00e9uticos en Hepatolog\u00eda\u201d. El comit\u00e9 organizador tuvo al Dr. Adri\u00e1n Gadano como presidente y al Dr. Ezequiel Ridruejo como vicepresidente. Como invitados [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13898","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Simposio Internacional de Hepatolog\u00eda 2016 - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alehlatam.org\/en\/simposio-internacional-de-hepatologia-2016-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Simposio Internacional de Hepatolog\u00eda 2016 - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"og:description\" content=\"Nuevos Horizontes Terap\u00e9uticos en Hepatolog\u00eda. Buenos Aires Argentina. Con gran \u00e9xito y numerosa asistencia se realiz\u00f3, del 22 al 24 de junio, en Buenos Aires Argentina, el Simposio Internacional de Hepatolog\u00eda, \u201cNuevos Horizontes Terap\u00e9uticos en Hepatolog\u00eda\u201d. El comit\u00e9 organizador tuvo al Dr. Adri\u00e1n Gadano como presidente y al Dr. Ezequiel Ridruejo como vicepresidente. Como invitados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alehlatam.org\/en\/simposio-internacional-de-hepatologia-2016-3\/\" \/>\n<meta property=\"og:site_name\" content=\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-21T04:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alehlatam.org\/wp-content\/uploads\/2026\/01\/Default-banner-para-links-externos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/simposio-internacional-de-hepatologia-2016-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/simposio-internacional-de-hepatologia-2016-3\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\"},\"headline\":\"Simposio Internacional de Hepatolog\u00eda 2016\",\"datePublished\":\"2016-07-21T04:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/simposio-internacional-de-hepatologia-2016-3\\\/\"},\"wordCount\":117,\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/simposio-internacional-de-hepatologia-2016-3\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/simposio-internacional-de-hepatologia-2016-3\\\/\",\"name\":\"Simposio Internacional de Hepatolog\u00eda 2016 - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\"},\"datePublished\":\"2016-07-21T04:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/simposio-internacional-de-hepatologia-2016-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alehlatam.org\\\/simposio-internacional-de-hepatologia-2016-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/simposio-internacional-de-hepatologia-2016-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/alehlatam.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Simposio Internacional de Hepatolog\u00eda 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"name\":\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"description\":\"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.\",\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"alternateName\":\"ALEH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alehlatam.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\",\"name\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"alternateName\":\"ALEH\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"width\":2000,\"height\":1493,\"caption\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/alehlatam.org\"],\"url\":\"https:\\\/\\\/alehlatam.org\\\/en\\\/author\\\/admin-eventual\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Simposio Internacional de Hepatolog\u00eda 2016 - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alehlatam.org\/en\/simposio-internacional-de-hepatologia-2016-3\/","og_locale":"en_US","og_type":"article","og_title":"Simposio Internacional de Hepatolog\u00eda 2016 - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","og_description":"Nuevos Horizontes Terap\u00e9uticos en Hepatolog\u00eda. Buenos Aires Argentina. Con gran \u00e9xito y numerosa asistencia se realiz\u00f3, del 22 al 24 de junio, en Buenos Aires Argentina, el Simposio Internacional de Hepatolog\u00eda, \u201cNuevos Horizontes Terap\u00e9uticos en Hepatolog\u00eda\u201d. El comit\u00e9 organizador tuvo al Dr. Adri\u00e1n Gadano como presidente y al Dr. Ezequiel Ridruejo como vicepresidente. Como invitados [&hellip;]","og_url":"https:\/\/alehlatam.org\/en\/simposio-internacional-de-hepatologia-2016-3\/","og_site_name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","article_published_time":"2016-07-21T04:00:00+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2026\/01\/Default-banner-para-links-externos.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alehlatam.org\/simposio-internacional-de-hepatologia-2016-3\/#article","isPartOf":{"@id":"https:\/\/alehlatam.org\/simposio-internacional-de-hepatologia-2016-3\/"},"author":{"name":"admin","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f"},"headline":"Simposio Internacional de Hepatolog\u00eda 2016","datePublished":"2016-07-21T04:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/alehlatam.org\/simposio-internacional-de-hepatologia-2016-3\/"},"wordCount":117,"publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/alehlatam.org\/simposio-internacional-de-hepatologia-2016-3\/","url":"https:\/\/alehlatam.org\/simposio-internacional-de-hepatologia-2016-3\/","name":"Simposio Internacional de Hepatolog\u00eda 2016 - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","isPartOf":{"@id":"https:\/\/alehlatam.org\/#website"},"datePublished":"2016-07-21T04:00:00+00:00","breadcrumb":{"@id":"https:\/\/alehlatam.org\/simposio-internacional-de-hepatologia-2016-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alehlatam.org\/simposio-internacional-de-hepatologia-2016-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alehlatam.org\/simposio-internacional-de-hepatologia-2016-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/alehlatam.org\/"},{"@type":"ListItem","position":2,"name":"Simposio Internacional de Hepatolog\u00eda 2016"}]},{"@type":"WebSite","@id":"https:\/\/alehlatam.org\/#website","url":"https:\/\/alehlatam.org\/","name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","description":"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.","publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"alternateName":"ALEH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alehlatam.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/alehlatam.org\/#organization","name":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","alternateName":"ALEH","url":"https:\/\/alehlatam.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","width":2000,"height":1493,"caption":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado"},"image":{"@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/alehlatam.org"],"url":"https:\/\/alehlatam.org\/en\/author\/admin-eventual\/"}]}},"_links":{"self":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/posts\/13898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/comments?post=13898"}],"version-history":[{"count":0,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/posts\/13898\/revisions"}],"wp:attachment":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/media?parent=13898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/categories?post=13898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/tags?post=13898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}