{"id":14060,"date":"2017-08-11T00:00:00","date_gmt":"2017-08-11T04:00:00","guid":{"rendered":"https:\/\/alehlatam.org\/wp2024\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/"},"modified":"2017-08-11T00:00:00","modified_gmt":"2017-08-11T04:00:00","slug":"dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc","status":"publish","type":"post","link":"https:\/\/alehlatam.org\/en\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/","title":{"rendered":"Dr. Flair Carrilho ser\u00e1 nombrado Acad\u00e9mico de Honor en la RAMC"},"content":{"rendered":"<p>El d\u00eda martes 19 de septiembre, la Real Academia de Medicina de Catalu\u00f1a, celebrar\u00e1 sesi\u00f3n extraordinaria para la recepci\u00f3n del Acad\u00e9mico de Honor, Dr. Flair Jos\u00e9 Carrilho, quien disertar\u00e1 sobre el tema: \u201cLa influencia del Hospital Clinic y del Hospital Sant Pau de Barcelona en la formaci\u00f3n de especialistas de Gastroenterolog\u00eda y Hepatolog\u00eda de Brasil\u201d.<\/p>\n<p>Esta actividad ser\u00e1 presentada por el Acad\u00e9mico Numerario, Dr. Miquel Bruguera i Cortada, y finalizando el acto, se le entregar\u00e1 al Dr. Flair Carrilho, el diploma Acad\u00e9mico de Honor.<br \/>\nEsta noticia llena de orgullo y regocijo a la hepatolog\u00eda latinoamericana, y es un ejemplo de lo que somos capaces de lograr. Sin duda, el Dr. Flair Carrilho es un excelente modelo a seguir por los j\u00f3venes hepat\u00f3logos de ALEH.<\/p>\n<p><a href=\"http:\/\/alehlatam.org\/en\/RAMC-Apresentacao-Flair.pdf\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ver m\u00e1s sobre la RAMC y el Dr. Flair Carrilho<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El d\u00eda martes 19 de septiembre, la Real Academia de Medicina de Catalu\u00f1a, celebrar\u00e1 sesi\u00f3n extraordinaria para la recepci\u00f3n del Acad\u00e9mico de Honor, Dr. Flair Jos\u00e9 Carrilho, quien disertar\u00e1 sobre el tema: \u201cLa influencia del Hospital Clinic y del Hospital Sant Pau de Barcelona en la formaci\u00f3n de especialistas de Gastroenterolog\u00eda y Hepatolog\u00eda de Brasil\u201d. [&hellip;]<\/p>","protected":false},"author":1,"featured_media":14061,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dr. Flair Carrilho ser\u00e1 nombrado Acad\u00e9mico de Honor en la RAMC - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alehlatam.org\/en\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Flair Carrilho ser\u00e1 nombrado Acad\u00e9mico de Honor en la RAMC - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"og:description\" content=\"El d\u00eda martes 19 de septiembre, la Real Academia de Medicina de Catalu\u00f1a, celebrar\u00e1 sesi\u00f3n extraordinaria para la recepci\u00f3n del Acad\u00e9mico de Honor, Dr. Flair Jos\u00e9 Carrilho, quien disertar\u00e1 sobre el tema: \u201cLa influencia del Hospital Clinic y del Hospital Sant Pau de Barcelona en la formaci\u00f3n de especialistas de Gastroenterolog\u00eda y Hepatolog\u00eda de Brasil\u201d. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alehlatam.org\/en\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/\" \/>\n<meta property=\"og:site_name\" content=\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-11T04:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/flair-carrilho-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"645\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\"},\"headline\":\"Dr. Flair Carrilho ser\u00e1 nombrado Acad\u00e9mico de Honor en la RAMC\",\"datePublished\":\"2017-08-11T04:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\\\/\"},\"wordCount\":159,\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/flair-carrilho-1.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\\\/\",\"name\":\"Dr. Flair Carrilho ser\u00e1 nombrado Acad\u00e9mico de Honor en la RAMC - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/flair-carrilho-1.jpg\",\"datePublished\":\"2017-08-11T04:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alehlatam.org\\\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/flair-carrilho-1.jpg\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/flair-carrilho-1.jpg\",\"width\":1140,\"height\":645},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/alehlatam.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dr. Flair Carrilho ser\u00e1 nombrado Acad\u00e9mico de Honor en la RAMC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"name\":\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"description\":\"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.\",\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"alternateName\":\"ALEH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alehlatam.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\",\"name\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"alternateName\":\"ALEH\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"width\":2000,\"height\":1493,\"caption\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/alehlatam.org\"],\"url\":\"https:\\\/\\\/alehlatam.org\\\/en\\\/author\\\/admin-eventual\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Flair Carrilho ser\u00e1 nombrado Acad\u00e9mico de Honor en la RAMC - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alehlatam.org\/en\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/","og_locale":"en_US","og_type":"article","og_title":"Dr. Flair Carrilho ser\u00e1 nombrado Acad\u00e9mico de Honor en la RAMC - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","og_description":"El d\u00eda martes 19 de septiembre, la Real Academia de Medicina de Catalu\u00f1a, celebrar\u00e1 sesi\u00f3n extraordinaria para la recepci\u00f3n del Acad\u00e9mico de Honor, Dr. Flair Jos\u00e9 Carrilho, quien disertar\u00e1 sobre el tema: \u201cLa influencia del Hospital Clinic y del Hospital Sant Pau de Barcelona en la formaci\u00f3n de especialistas de Gastroenterolog\u00eda y Hepatolog\u00eda de Brasil\u201d. [&hellip;]","og_url":"https:\/\/alehlatam.org\/en\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/","og_site_name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","article_published_time":"2017-08-11T04:00:00+00:00","og_image":[{"width":1140,"height":645,"url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/flair-carrilho-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alehlatam.org\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/#article","isPartOf":{"@id":"https:\/\/alehlatam.org\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/"},"author":{"name":"admin","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f"},"headline":"Dr. Flair Carrilho ser\u00e1 nombrado Acad\u00e9mico de Honor en la RAMC","datePublished":"2017-08-11T04:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/alehlatam.org\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/"},"wordCount":159,"publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"image":{"@id":"https:\/\/alehlatam.org\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/#primaryimage"},"thumbnailUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/flair-carrilho-1.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/alehlatam.org\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/","url":"https:\/\/alehlatam.org\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/","name":"Dr. Flair Carrilho ser\u00e1 nombrado Acad\u00e9mico de Honor en la RAMC - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","isPartOf":{"@id":"https:\/\/alehlatam.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alehlatam.org\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/#primaryimage"},"image":{"@id":"https:\/\/alehlatam.org\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/#primaryimage"},"thumbnailUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/flair-carrilho-1.jpg","datePublished":"2017-08-11T04:00:00+00:00","breadcrumb":{"@id":"https:\/\/alehlatam.org\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alehlatam.org\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alehlatam.org\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/#primaryimage","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/flair-carrilho-1.jpg","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/flair-carrilho-1.jpg","width":1140,"height":645},{"@type":"BreadcrumbList","@id":"https:\/\/alehlatam.org\/dr-flair-carrilho-sera-nombrado-academico-de-honor-en-la-ramc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/alehlatam.org\/"},{"@type":"ListItem","position":2,"name":"Dr. Flair Carrilho ser\u00e1 nombrado Acad\u00e9mico de Honor en la RAMC"}]},{"@type":"WebSite","@id":"https:\/\/alehlatam.org\/#website","url":"https:\/\/alehlatam.org\/","name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","description":"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.","publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"alternateName":"ALEH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alehlatam.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/alehlatam.org\/#organization","name":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","alternateName":"ALEH","url":"https:\/\/alehlatam.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","width":2000,"height":1493,"caption":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado"},"image":{"@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/alehlatam.org"],"url":"https:\/\/alehlatam.org\/en\/author\/admin-eventual\/"}]}},"_links":{"self":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/posts\/14060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/comments?post=14060"}],"version-history":[{"count":0,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/posts\/14060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/media\/14061"}],"wp:attachment":[{"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/media?parent=14060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/categories?post=14060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alehlatam.org\/en\/wp-json\/wp\/v2\/tags?post=14060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}