{"id":13909,"date":"2017-05-04T00:00:00","date_gmt":"2017-05-04T03:00:00","guid":{"rendered":"https:\/\/alehlatam.org\/wp2024\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/"},"modified":"2017-05-04T00:00:00","modified_gmt":"2017-05-04T03:00:00","slug":"alianza-entre-aleh-y-el-grupo-amhigos-del-higado","status":"publish","type":"post","link":"https:\/\/alehlatam.org\/pt\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/","title":{"rendered":"Alianza entre ALEH y el Grupo Amhigos del H\u00edgado"},"content":{"rendered":"<p>Dando seguimiento al compromiso\u00a0adquirido entre de la Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado y\u00a0AMHIGO, en esta ocasi\u00f3n les\u00a0compartiremos\u00a0la rese\u00f1a enviada\u00a0por el Dr. Jorge Luis Poo, sobre qu\u00e9\u00a0es AMHIGO, c\u00f3mo surge, su trayectoria, objetivos y logros.\u00a0 Los invitamos a que lean esta interesante y motivadora iniciativa que esperemos\u00a0sirva de modelo a implementar en sus distintos pa\u00edses para beneficio de nuestros pacientes<\/p>\n<blockquote><p><span style=\"color: #808080;\">Prezados colegas:<\/span><\/p>\n<p><span style=\"color: #808080;\">En esta ocasi\u00f3n tenemos el gusto de presentarles a AMHIGO, un proyecto educativo virtual que surgi\u00f3 en la Ciudad de M\u00e9xico, all\u00e1 por el a\u00f1o de 2014, cuando un peque\u00f1o grupo de m\u00e9dicos se percataron de la importancia del tiempo dedicado a explicar a los pacientes sobre el origen de su enfermedad, la evoluci\u00f3n natural, las posibles complicaciones, la importancia de realizarse y entender sus estudios, as\u00ed como el lograr un buen apego a la terap\u00e9utica, todo lo cual podr\u00eda ayudarles a mejorar su calidad de vida y prevenir complicaciones.<\/span><\/p>\n<p><span style=\"color: #808080;\">Poco a poco, la opci\u00f3n presencial de cursos en salones o auditorios abri\u00f3 una puerta al mundo virtual, en donde los pacientes, familiares y amigos pueden acceder a informaci\u00f3n sobre la salud hep\u00e1tica a cualquier hora y todos los d\u00edas de la semana, por el simple hecho de teclear\u00a0<a style=\"color: #808080;\" href=\"http:\/\/www.amhigo.com\">www.amhigo.com<\/a>.<\/span><\/p>\n<p><span style=\"color: #808080;\">AMHIGO incluye 7 m\u00f3dulos interactivos, 70 secciones, un carrusel de noticias de primera plana, m\u00e1s de 300 fotos y\/o diagramas educativos, un noticiero semanal con 10 categor\u00edas del inmenso mundo de la salud hep\u00e1tica, con m\u00e1s de 500 noticias m\u00e9dicas acumuladas, 7 calculadoras en l\u00ednea con representaci\u00f3n gr\u00e1fica de sus resultados que suman m\u00e1s de 5000 consultas en l\u00ednea, 6 encuestas de apego a dieta, ejercicio y\/o medicamentos, videos, testimonios, blogs e interacci\u00f3n con redes sociales.<\/span><\/p>\n<p><span style=\"color: #808080;\">Por todo ello, te invitamos a visitar el portal AMHIGO, una plataforma virtual educativa, informativa e interactiva, motivada por el amor al paciente y con el esp\u00edritu de mejorar continuamente en sus contenidos. Su enfoque es amigable, un poco acad\u00e9mico, pero a la vez sencillo, temas serios y a la vez divertidos, que describen contenidos eternos (anatom\u00eda y fisiolog\u00eda del h\u00edgado), de vanguardia (los nuevos antivirales de acci\u00f3n directa contra el VHC) e incluso de arte para acariciar los sentidos.<\/span><\/p>\n<p><span style=\"color: #808080;\">Visita:\u00a0<a style=\"color: #808080;\" href=\"http:\/\/www.amhigo.mx\" target=\"_blank\" rel=\"noopener noreferrer\">www.amhigo.mx<\/a><\/span><\/p><\/blockquote>","protected":false},"excerpt":{"rendered":"<p>Dando seguimiento al compromiso\u00a0adquirido entre de la Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado y\u00a0AMHIGO, en esta ocasi\u00f3n les\u00a0compartiremos\u00a0la rese\u00f1a enviada\u00a0por el Dr. Jorge Luis Poo, sobre qu\u00e9\u00a0es AMHIGO, c\u00f3mo surge, su trayectoria, objetivos y logros.\u00a0 Los invitamos a que lean esta interesante y motivadora iniciativa que esperemos\u00a0sirva de modelo a implementar en sus distintos [&hellip;]<\/p>","protected":false},"author":1,"featured_media":13859,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alianza entre ALEH y el Grupo Amhigos del H\u00edgado - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alehlatam.org\/pt\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alianza entre ALEH y el Grupo Amhigos del H\u00edgado - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"og:description\" content=\"Dando seguimiento al compromiso\u00a0adquirido entre de la Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado y\u00a0AMHIGO, en esta ocasi\u00f3n les\u00a0compartiremos\u00a0la rese\u00f1a enviada\u00a0por el Dr. Jorge Luis Poo, sobre qu\u00e9\u00a0es AMHIGO, c\u00f3mo surge, su trayectoria, objetivos y logros.\u00a0 Los invitamos a que lean esta interesante y motivadora iniciativa que esperemos\u00a0sirva de modelo a implementar en sus distintos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alehlatam.org\/pt\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/\" \/>\n<meta property=\"og:site_name\" content=\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-04T03:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/amhigo-acuerdo-aleh.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"645\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\"},\"headline\":\"Alianza entre ALEH y el Grupo Amhigos del H\u00edgado\",\"datePublished\":\"2017-05-04T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\\\/\"},\"wordCount\":411,\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/amhigo-acuerdo-aleh.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\\\/\",\"name\":\"Alianza entre ALEH y el Grupo Amhigos del H\u00edgado - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/amhigo-acuerdo-aleh.jpg\",\"datePublished\":\"2017-05-04T03:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alehlatam.org\\\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/amhigo-acuerdo-aleh.jpg\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/amhigo-acuerdo-aleh.jpg\",\"width\":1140,\"height\":645},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/alehlatam.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alianza entre ALEH y el Grupo Amhigos del H\u00edgado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"name\":\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"description\":\"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.\",\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"alternateName\":\"ALEH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alehlatam.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\",\"name\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"alternateName\":\"ALEH\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"width\":2000,\"height\":1493,\"caption\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/alehlatam.org\"],\"url\":\"https:\\\/\\\/alehlatam.org\\\/pt\\\/author\\\/admin-eventual\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alianza entre ALEH y el Grupo Amhigos del H\u00edgado - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alehlatam.org\/pt\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/","og_locale":"pt_BR","og_type":"article","og_title":"Alianza entre ALEH y el Grupo Amhigos del H\u00edgado - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","og_description":"Dando seguimiento al compromiso\u00a0adquirido entre de la Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado y\u00a0AMHIGO, en esta ocasi\u00f3n les\u00a0compartiremos\u00a0la rese\u00f1a enviada\u00a0por el Dr. Jorge Luis Poo, sobre qu\u00e9\u00a0es AMHIGO, c\u00f3mo surge, su trayectoria, objetivos y logros.\u00a0 Los invitamos a que lean esta interesante y motivadora iniciativa que esperemos\u00a0sirva de modelo a implementar en sus distintos [&hellip;]","og_url":"https:\/\/alehlatam.org\/pt\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/","og_site_name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","article_published_time":"2017-05-04T03:00:00+00:00","og_image":[{"width":1140,"height":645,"url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/amhigo-acuerdo-aleh.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alehlatam.org\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/#article","isPartOf":{"@id":"https:\/\/alehlatam.org\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/"},"author":{"name":"admin","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f"},"headline":"Alianza entre ALEH y el Grupo Amhigos del H\u00edgado","datePublished":"2017-05-04T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/alehlatam.org\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/"},"wordCount":411,"publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"image":{"@id":"https:\/\/alehlatam.org\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/#primaryimage"},"thumbnailUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/amhigo-acuerdo-aleh.jpg","articleSection":["Uncategorized"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/alehlatam.org\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/","url":"https:\/\/alehlatam.org\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/","name":"Alianza entre ALEH y el Grupo Amhigos del H\u00edgado - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","isPartOf":{"@id":"https:\/\/alehlatam.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alehlatam.org\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/#primaryimage"},"image":{"@id":"https:\/\/alehlatam.org\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/#primaryimage"},"thumbnailUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/amhigo-acuerdo-aleh.jpg","datePublished":"2017-05-04T03:00:00+00:00","breadcrumb":{"@id":"https:\/\/alehlatam.org\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alehlatam.org\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alehlatam.org\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/#primaryimage","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/amhigo-acuerdo-aleh.jpg","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/amhigo-acuerdo-aleh.jpg","width":1140,"height":645},{"@type":"BreadcrumbList","@id":"https:\/\/alehlatam.org\/alianza-entre-aleh-y-el-grupo-amhigos-del-higado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/alehlatam.org\/"},{"@type":"ListItem","position":2,"name":"Alianza entre ALEH y el Grupo Amhigos del H\u00edgado"}]},{"@type":"WebSite","@id":"https:\/\/alehlatam.org\/#website","url":"https:\/\/alehlatam.org\/","name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","description":"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.","publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"alternateName":"ALEH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alehlatam.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/alehlatam.org\/#organization","name":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","alternateName":"ALEH","url":"https:\/\/alehlatam.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","width":2000,"height":1493,"caption":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado"},"image":{"@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/alehlatam.org"],"url":"https:\/\/alehlatam.org\/pt\/author\/admin-eventual\/"}]}},"_links":{"self":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts\/13909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/comments?post=13909"}],"version-history":[{"count":0,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts\/13909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/media\/13859"}],"wp:attachment":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/media?parent=13909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/categories?post=13909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/tags?post=13909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}