{"id":13954,"date":"2017-06-13T00:00:00","date_gmt":"2017-06-13T04:00:00","guid":{"rendered":"https:\/\/alehlatam.org\/wp2024\/exitosa-reunion-del-grupo-de-interes-dili\/"},"modified":"2017-06-13T00:00:00","modified_gmt":"2017-06-13T04:00:00","slug":"exitosa-reunion-del-grupo-de-interes-dili","status":"publish","type":"post","link":"https:\/\/alehlatam.org\/pt\/exitosa-reunion-del-grupo-de-interes-dili\/","title":{"rendered":"Exitosa reuni\u00f3n del Grupo de Inter\u00e9s DILI"},"content":{"rendered":"<p>En el pasado Congreso EASL, realizado en el mes de abril en Amsterdam, se reuni\u00f3 nuestro Grupo de Inter\u00e9s de Hepatotoxicidad, en la cual el Dr. Fernando Bessone (Argentina), coordinador del\u00a0Latin American DILI Registry, present\u00f3 el estado actual del registro latinoamericano, mostrando el n\u00famero de casos reclutados por pa\u00eds y remarcando los puntos fuertes y d\u00e9biles que fueron detectados en la inclusi\u00f3n de pacientes con presunto diagn\u00f3stico de DILI. Debido a que se mantiene una distribuci\u00f3n muy heterog\u00e9nea de env\u00edos en Latinoam\u00e9rica, la cual podr\u00eda no ser representativa de toda la zona analizada, se propone estimular e incluir nuevos pa\u00edses y a su vez, elevar el n\u00famero de casos por pa\u00eds, de aquellos ya incorporados al registro, como el objetivo m\u00e1s importante de esta reuni\u00f3n.<\/p>\n<p>Para ver el resumen completo de la reuni\u00f3n, <a href=\"http:\/\/alehlatam.org\/wp-content\/uploads\/2017\/06\/Memoria-de-la-reunion-19-de-abril-2017-GRUPO-DILI-EASL-AMSTERDAM-20172.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>ingrese aqu\u00ed<\/strong><\/a><\/p>\n<p>Revise la informaci\u00f3n sobre <a href=\"http:\/\/alehlatam.org\/wp-content\/uploads\/2017\/06\/Criterios-diagno\u0301sticos-de-DILI-para-ALEH.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Criterios estandarizados para diagnosticar y clasificar la toxicidad hep\u00e1tica en el contexto del registro<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>En el pasado Congreso EASL, realizado en el mes de abril en Amsterdam, se reuni\u00f3 nuestro Grupo de Inter\u00e9s de Hepatotoxicidad, en la cual el Dr. Fernando Bessone (Argentina), coordinador del\u00a0Latin American DILI Registry, present\u00f3 el estado actual del registro latinoamericano, mostrando el n\u00famero de casos reclutados por pa\u00eds y remarcando los puntos fuertes y [&hellip;]<\/p>","protected":false},"author":1,"featured_media":13955,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exitosa reuni\u00f3n del Grupo de Inter\u00e9s DILI - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alehlatam.org\/pt\/exitosa-reunion-del-grupo-de-interes-dili\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exitosa reuni\u00f3n del Grupo de Inter\u00e9s DILI - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"og:description\" content=\"En el pasado Congreso EASL, realizado en el mes de abril en Amsterdam, se reuni\u00f3 nuestro Grupo de Inter\u00e9s de Hepatotoxicidad, en la cual el Dr. Fernando Bessone (Argentina), coordinador del\u00a0Latin American DILI Registry, present\u00f3 el estado actual del registro latinoamericano, mostrando el n\u00famero de casos reclutados por pa\u00eds y remarcando los puntos fuertes y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alehlatam.org\/pt\/exitosa-reunion-del-grupo-de-interes-dili\/\" \/>\n<meta property=\"og:site_name\" content=\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-13T04:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/reunion-dili.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"645\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/exitosa-reunion-del-grupo-de-interes-dili\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/exitosa-reunion-del-grupo-de-interes-dili\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\"},\"headline\":\"Exitosa reuni\u00f3n del Grupo de Inter\u00e9s DILI\",\"datePublished\":\"2017-06-13T04:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/exitosa-reunion-del-grupo-de-interes-dili\\\/\"},\"wordCount\":182,\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/exitosa-reunion-del-grupo-de-interes-dili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/reunion-dili.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/exitosa-reunion-del-grupo-de-interes-dili\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/exitosa-reunion-del-grupo-de-interes-dili\\\/\",\"name\":\"Exitosa reuni\u00f3n del Grupo de Inter\u00e9s DILI - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/exitosa-reunion-del-grupo-de-interes-dili\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/exitosa-reunion-del-grupo-de-interes-dili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/reunion-dili.jpg\",\"datePublished\":\"2017-06-13T04:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/exitosa-reunion-del-grupo-de-interes-dili\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alehlatam.org\\\/exitosa-reunion-del-grupo-de-interes-dili\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/exitosa-reunion-del-grupo-de-interes-dili\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/reunion-dili.jpg\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/reunion-dili.jpg\",\"width\":1140,\"height\":645},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/exitosa-reunion-del-grupo-de-interes-dili\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/alehlatam.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exitosa reuni\u00f3n del Grupo de Inter\u00e9s DILI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"name\":\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"description\":\"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.\",\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"alternateName\":\"ALEH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alehlatam.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\",\"name\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"alternateName\":\"ALEH\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"width\":2000,\"height\":1493,\"caption\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/alehlatam.org\"],\"url\":\"https:\\\/\\\/alehlatam.org\\\/pt\\\/author\\\/admin-eventual\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exitosa reuni\u00f3n del Grupo de Inter\u00e9s DILI - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alehlatam.org\/pt\/exitosa-reunion-del-grupo-de-interes-dili\/","og_locale":"pt_BR","og_type":"article","og_title":"Exitosa reuni\u00f3n del Grupo de Inter\u00e9s DILI - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","og_description":"En el pasado Congreso EASL, realizado en el mes de abril en Amsterdam, se reuni\u00f3 nuestro Grupo de Inter\u00e9s de Hepatotoxicidad, en la cual el Dr. Fernando Bessone (Argentina), coordinador del\u00a0Latin American DILI Registry, present\u00f3 el estado actual del registro latinoamericano, mostrando el n\u00famero de casos reclutados por pa\u00eds y remarcando los puntos fuertes y [&hellip;]","og_url":"https:\/\/alehlatam.org\/pt\/exitosa-reunion-del-grupo-de-interes-dili\/","og_site_name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","article_published_time":"2017-06-13T04:00:00+00:00","og_image":[{"width":1140,"height":645,"url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/reunion-dili.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alehlatam.org\/exitosa-reunion-del-grupo-de-interes-dili\/#article","isPartOf":{"@id":"https:\/\/alehlatam.org\/exitosa-reunion-del-grupo-de-interes-dili\/"},"author":{"name":"admin","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f"},"headline":"Exitosa reuni\u00f3n del Grupo de Inter\u00e9s DILI","datePublished":"2017-06-13T04:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/alehlatam.org\/exitosa-reunion-del-grupo-de-interes-dili\/"},"wordCount":182,"publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"image":{"@id":"https:\/\/alehlatam.org\/exitosa-reunion-del-grupo-de-interes-dili\/#primaryimage"},"thumbnailUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/reunion-dili.jpg","articleSection":["Uncategorized"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/alehlatam.org\/exitosa-reunion-del-grupo-de-interes-dili\/","url":"https:\/\/alehlatam.org\/exitosa-reunion-del-grupo-de-interes-dili\/","name":"Exitosa reuni\u00f3n del Grupo de Inter\u00e9s DILI - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","isPartOf":{"@id":"https:\/\/alehlatam.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alehlatam.org\/exitosa-reunion-del-grupo-de-interes-dili\/#primaryimage"},"image":{"@id":"https:\/\/alehlatam.org\/exitosa-reunion-del-grupo-de-interes-dili\/#primaryimage"},"thumbnailUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/reunion-dili.jpg","datePublished":"2017-06-13T04:00:00+00:00","breadcrumb":{"@id":"https:\/\/alehlatam.org\/exitosa-reunion-del-grupo-de-interes-dili\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alehlatam.org\/exitosa-reunion-del-grupo-de-interes-dili\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alehlatam.org\/exitosa-reunion-del-grupo-de-interes-dili\/#primaryimage","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/reunion-dili.jpg","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/reunion-dili.jpg","width":1140,"height":645},{"@type":"BreadcrumbList","@id":"https:\/\/alehlatam.org\/exitosa-reunion-del-grupo-de-interes-dili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/alehlatam.org\/"},{"@type":"ListItem","position":2,"name":"Exitosa reuni\u00f3n del Grupo de Inter\u00e9s DILI"}]},{"@type":"WebSite","@id":"https:\/\/alehlatam.org\/#website","url":"https:\/\/alehlatam.org\/","name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","description":"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.","publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"alternateName":"ALEH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alehlatam.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/alehlatam.org\/#organization","name":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","alternateName":"ALEH","url":"https:\/\/alehlatam.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","width":2000,"height":1493,"caption":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado"},"image":{"@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/alehlatam.org"],"url":"https:\/\/alehlatam.org\/pt\/author\/admin-eventual\/"}]}},"_links":{"self":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts\/13954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/comments?post=13954"}],"version-history":[{"count":0,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts\/13954\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/media\/13955"}],"wp:attachment":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/media?parent=13954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/categories?post=13954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/tags?post=13954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}