{"id":13983,"date":"2017-07-11T00:00:00","date_gmt":"2017-07-11T04:00:00","guid":{"rendered":"https:\/\/alehlatam.org\/wp2024\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/"},"modified":"2024-03-18T15:56:47","modified_gmt":"2024-03-18T18:56:47","slug":"beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online","status":"publish","type":"post","link":"https:\/\/alehlatam.org\/pt\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/","title":{"rendered":"Beneficiarios de la Primera Beca ALEH al Curso de Hepatolog\u00eda Online"},"content":{"rendered":"<p>El d\u00eda 03 de julio se lanz\u00f3 la primera Beca ALEH para el Curso de Hepatolog\u00eda Online, la cual consisti\u00f3 en 05 inscripciones liberadas para los Socios ALEH. Los beneficiarios de esta beca fueron: Dra. Kriss del Roc\u00edo Rodr\u00edguez (Per\u00fa), Dr. Ricardo Chong (Ecuador), Dr. Isaac Ruiz (M\u00e9xico), Dr. Edwin Vicente (Rep\u00fablica Dominicana) y Dr. Gast\u00f3n Nieto (Uruguay),<br \/>\nEste curso fue creado por la Sociedad Chilena de Gastroenterolog\u00eda y la Sociedad M\u00e9dica de Santiago, el cual comenz\u00f3 el d\u00eda 06 de julio y consta de 05 m\u00f3dulos, dentro de los cuales se tratan temas como: hepatitis alcoh\u00f3lica, ascitis refrectaria, hepatocarcinoma, entre otros. La fecha de postulaci\u00f3n se extendi\u00f3 hasta el d\u00eda 28 de julio. Para revisar el programa completo, <a href=\"http:\/\/alehlatam.org\/pt\/investigacion-y-educacion\/curso-online-de-hepatologia-2017\/\" target=\"_blank\" rel=\"noopener noreferrer\">ingrese aqu\u00ed<\/a><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-3272 aligncenter\" src=\"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/ganadores-beca-curso-online-pais.jpg\" alt=\"\" width=\"600\" height=\"550\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>El d\u00eda 03 de julio se lanz\u00f3 la primera Beca ALEH para el Curso de Hepatolog\u00eda Online, la cual consisti\u00f3 en 05 inscripciones liberadas para los Socios ALEH. Los beneficiarios de esta beca fueron: Dra. Kriss del Roc\u00edo Rodr\u00edguez (Per\u00fa), Dr. Ricardo Chong (Ecuador), Dr. Isaac Ruiz (M\u00e9xico), Dr. Edwin Vicente (Rep\u00fablica Dominicana) y Dr. [&hellip;]<\/p>","protected":false},"author":1,"featured_media":13986,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beneficiarios de la Primera Beca ALEH al Curso de Hepatolog\u00eda Online - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alehlatam.org\/pt\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beneficiarios de la Primera Beca ALEH al Curso de Hepatolog\u00eda Online - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"og:description\" content=\"El d\u00eda 03 de julio se lanz\u00f3 la primera Beca ALEH para el Curso de Hepatolog\u00eda Online, la cual consisti\u00f3 en 05 inscripciones liberadas para los Socios ALEH. Los beneficiarios de esta beca fueron: Dra. Kriss del Roc\u00edo Rodr\u00edguez (Per\u00fa), Dr. Ricardo Chong (Ecuador), Dr. Isaac Ruiz (M\u00e9xico), Dr. Edwin Vicente (Rep\u00fablica Dominicana) y Dr. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alehlatam.org\/pt\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/\" \/>\n<meta property=\"og:site_name\" content=\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-11T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-18T18:56:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/baneficiarios-noticia-aleh.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"645\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\"},\"headline\":\"Beneficiarios de la Primera Beca ALEH al Curso de Hepatolog\u00eda Online\",\"datePublished\":\"2017-07-11T04:00:00+00:00\",\"dateModified\":\"2024-03-18T18:56:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\\\/\"},\"wordCount\":142,\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/baneficiarios-noticia-aleh.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\\\/\",\"name\":\"Beneficiarios de la Primera Beca ALEH al Curso de Hepatolog\u00eda Online - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/baneficiarios-noticia-aleh.jpg\",\"datePublished\":\"2017-07-11T04:00:00+00:00\",\"dateModified\":\"2024-03-18T18:56:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alehlatam.org\\\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/baneficiarios-noticia-aleh.jpg\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/baneficiarios-noticia-aleh.jpg\",\"width\":1140,\"height\":645},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/alehlatam.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beneficiarios de la Primera Beca ALEH al Curso de Hepatolog\u00eda Online\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"name\":\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"description\":\"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.\",\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"alternateName\":\"ALEH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alehlatam.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\",\"name\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"alternateName\":\"ALEH\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"width\":2000,\"height\":1493,\"caption\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/alehlatam.org\"],\"url\":\"https:\\\/\\\/alehlatam.org\\\/pt\\\/author\\\/admin-eventual\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beneficiarios de la Primera Beca ALEH al Curso de Hepatolog\u00eda Online - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alehlatam.org\/pt\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/","og_locale":"pt_BR","og_type":"article","og_title":"Beneficiarios de la Primera Beca ALEH al Curso de Hepatolog\u00eda Online - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","og_description":"El d\u00eda 03 de julio se lanz\u00f3 la primera Beca ALEH para el Curso de Hepatolog\u00eda Online, la cual consisti\u00f3 en 05 inscripciones liberadas para los Socios ALEH. Los beneficiarios de esta beca fueron: Dra. Kriss del Roc\u00edo Rodr\u00edguez (Per\u00fa), Dr. Ricardo Chong (Ecuador), Dr. Isaac Ruiz (M\u00e9xico), Dr. Edwin Vicente (Rep\u00fablica Dominicana) y Dr. [&hellip;]","og_url":"https:\/\/alehlatam.org\/pt\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/","og_site_name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","article_published_time":"2017-07-11T04:00:00+00:00","article_modified_time":"2024-03-18T18:56:47+00:00","og_image":[{"width":1140,"height":645,"url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/baneficiarios-noticia-aleh.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alehlatam.org\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/#article","isPartOf":{"@id":"https:\/\/alehlatam.org\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/"},"author":{"name":"admin","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f"},"headline":"Beneficiarios de la Primera Beca ALEH al Curso de Hepatolog\u00eda Online","datePublished":"2017-07-11T04:00:00+00:00","dateModified":"2024-03-18T18:56:47+00:00","mainEntityOfPage":{"@id":"https:\/\/alehlatam.org\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/"},"wordCount":142,"publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"image":{"@id":"https:\/\/alehlatam.org\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/#primaryimage"},"thumbnailUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/baneficiarios-noticia-aleh.jpg","articleSection":["Uncategorized"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/alehlatam.org\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/","url":"https:\/\/alehlatam.org\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/","name":"Beneficiarios de la Primera Beca ALEH al Curso de Hepatolog\u00eda Online - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","isPartOf":{"@id":"https:\/\/alehlatam.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alehlatam.org\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/#primaryimage"},"image":{"@id":"https:\/\/alehlatam.org\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/#primaryimage"},"thumbnailUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/baneficiarios-noticia-aleh.jpg","datePublished":"2017-07-11T04:00:00+00:00","dateModified":"2024-03-18T18:56:47+00:00","breadcrumb":{"@id":"https:\/\/alehlatam.org\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alehlatam.org\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alehlatam.org\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/#primaryimage","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/baneficiarios-noticia-aleh.jpg","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/baneficiarios-noticia-aleh.jpg","width":1140,"height":645},{"@type":"BreadcrumbList","@id":"https:\/\/alehlatam.org\/beneficiarios-de-la-primera-beca-aleh-al-curso-de-hepatologia-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/alehlatam.org\/"},{"@type":"ListItem","position":2,"name":"Beneficiarios de la Primera Beca ALEH al Curso de Hepatolog\u00eda Online"}]},{"@type":"WebSite","@id":"https:\/\/alehlatam.org\/#website","url":"https:\/\/alehlatam.org\/","name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","description":"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.","publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"alternateName":"ALEH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alehlatam.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/alehlatam.org\/#organization","name":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","alternateName":"ALEH","url":"https:\/\/alehlatam.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","width":2000,"height":1493,"caption":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado"},"image":{"@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/alehlatam.org"],"url":"https:\/\/alehlatam.org\/pt\/author\/admin-eventual\/"}]}},"_links":{"self":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts\/13983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/comments?post=13983"}],"version-history":[{"count":0,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts\/13983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/media\/13986"}],"wp:attachment":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/media?parent=13983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/categories?post=13983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/tags?post=13983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}