{"id":14156,"date":"2017-11-04T00:00:00","date_gmt":"2017-11-04T03:00:00","guid":{"rendered":"https:\/\/alehlatam.org\/wp2024\/aleh-participa-en-el-world-hepatitis-summit\/"},"modified":"2017-11-04T00:00:00","modified_gmt":"2017-11-04T03:00:00","slug":"aleh-participa-en-el-world-hepatitis-summit","status":"publish","type":"post","link":"https:\/\/alehlatam.org\/pt\/aleh-participa-en-el-world-hepatitis-summit\/","title":{"rendered":"ALEH participa en el World Hepatitis Summit"},"content":{"rendered":"<p>El WORLD HEPATITIS SUMMIT, se celebr\u00f3 del 01 al 03 de noviembre en S\u00e3o Paulo, Brasil.<\/p>\n<p>El tema del WORLD HEPATITIS SUMMIT 2017 en S\u00e3o Paulo, fue\u00a0<em>Implementing the Global Health Sector Strategy on Viral Hepatitis (GHSS): Towards the elimination of hepatitis as a public health threat.<\/em><\/p>\n<p>ALEH fue invitado a una discusi\u00f3n paralela con AASLD, EASL y APASL para discutir el papel de las sociedades de h\u00edgado hacia la eliminaci\u00f3n de la hepatitis viral.<\/p>\n<p>Esta actividad es un evento bienal global a gran escala para avanzar en la agenda de la hepatitis viral. Es una iniciativa conjunta entre la Organizaci\u00f3n Mundial de la Salud (OMS) y la Alianza Mundial contra la Hepatitis, en colaboraci\u00f3n con un pa\u00eds anfitri\u00f3n diferente para cada Cumbre, en esta oportunidad, Brasil.<\/p>\n<p>El\u00a0WORLD HEPATITIS SUMMIT es un evento de tres d\u00edas de pol\u00edtica p\u00fablica que re\u00fane a una audiencia mundial de grupos de la sociedad civil, la OMS y sus estados miembros, organizaciones de pacientes de la Alianza Mundial contra la Hepatitis, responsables pol\u00edticos, cient\u00edficos de salud p\u00fablica y patrocinadores.<br \/>\nSus objetivos:<br \/>\n1. Aumentar el n\u00famero de pa\u00edses que desarrollan planes de acci\u00f3n de hepatitis viral practicables haciendo uso de la \u00faltima investigaci\u00f3n de salud p\u00fablica y el apoyo t\u00e9cnico de la OMS.<br \/>\n2. Mejorar la implementaci\u00f3n de los planes de acci\u00f3n de hepatitis viral existentes mediante el intercambio de las mejores pr\u00e1cticas.<br \/>\n3. Apoyar la resoluci\u00f3n de la OMS que insta a los Estados Miembros a \u00abpromover la participaci\u00f3n de la sociedad civil en todos los aspectos de prevenci\u00f3n, diagn\u00f3stico y tratamiento de la hepatitis viral\u00bb.<br \/>\n4. Discutir los mecanismos de financiamiento para medicinas y \/ o diagn\u00f3sticos a trav\u00e9s de la participaci\u00f3n de las partes interesadas clave.<br \/>\n5. Elevar el perfil de la hepatitis viral mediante el compromiso de medios internacionales de primer nivel.<br \/>\n6. Alentar y dirigir la investigaci\u00f3n de salud p\u00fablica hacia donde se necesita, involucrando a los principales proveedores de fondos globales.<br \/>\nSe firm\u00f3 un documento muy importante durante esta reuni\u00f3n: \u00ab<a href=\"http:\/\/alehlatam.org\/wp-content\/uploads\/2017\/11\/sao-paulo-declaration-on-hepatitis2.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><u>DECLARACI\u00d3N DE S\u00c3O PAULO SOBRE LA HEPATITIS<\/u><\/a>\u00ab, el cual reconoce la necesidad de un enfoque global para eliminar la hepatitis viral como un problema de salud p\u00fablica mediante la prevenci\u00f3n, diagn\u00f3stico, tratamiento y vigilancia de todas las formas de hepatitis viral &#8211; con un enfoque especial en las hepatitis virales B y C, que tienen las tasas m\u00e1s altas de morbilidad y mortalidad<\/p>","protected":false},"excerpt":{"rendered":"<p>El WORLD HEPATITIS SUMMIT, se celebr\u00f3 del 01 al 03 de noviembre en S\u00e3o Paulo, Brasil. El tema del WORLD HEPATITIS SUMMIT 2017 en S\u00e3o Paulo, fue\u00a0Implementing the Global Health Sector Strategy on Viral Hepatitis (GHSS): Towards the elimination of hepatitis as a public health threat. ALEH fue invitado a una discusi\u00f3n paralela con AASLD, [&hellip;]<\/p>","protected":false},"author":1,"featured_media":14154,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALEH participa en el World Hepatitis Summit - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alehlatam.org\/pt\/aleh-participa-en-el-world-hepatitis-summit\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALEH participa en el World Hepatitis Summit - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"og:description\" content=\"El WORLD HEPATITIS SUMMIT, se celebr\u00f3 del 01 al 03 de noviembre en S\u00e3o Paulo, Brasil. El tema del WORLD HEPATITIS SUMMIT 2017 en S\u00e3o Paulo, fue\u00a0Implementing the Global Health Sector Strategy on Viral Hepatitis (GHSS): Towards the elimination of hepatitis as a public health threat. ALEH fue invitado a una discusi\u00f3n paralela con AASLD, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alehlatam.org\/pt\/aleh-participa-en-el-world-hepatitis-summit\/\" \/>\n<meta property=\"og:site_name\" content=\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-04T03:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/aleh-world-hepatitis-summit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"645\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/aleh-participa-en-el-world-hepatitis-summit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/aleh-participa-en-el-world-hepatitis-summit\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\"},\"headline\":\"ALEH participa en el World Hepatitis Summit\",\"datePublished\":\"2017-11-04T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/aleh-participa-en-el-world-hepatitis-summit\\\/\"},\"wordCount\":433,\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/aleh-participa-en-el-world-hepatitis-summit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/aleh-world-hepatitis-summit.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/aleh-participa-en-el-world-hepatitis-summit\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/aleh-participa-en-el-world-hepatitis-summit\\\/\",\"name\":\"ALEH participa en el World Hepatitis Summit - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/aleh-participa-en-el-world-hepatitis-summit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/aleh-participa-en-el-world-hepatitis-summit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/aleh-world-hepatitis-summit.jpg\",\"datePublished\":\"2017-11-04T03:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/aleh-participa-en-el-world-hepatitis-summit\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alehlatam.org\\\/aleh-participa-en-el-world-hepatitis-summit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/aleh-participa-en-el-world-hepatitis-summit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/aleh-world-hepatitis-summit.jpg\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/aleh-world-hepatitis-summit.jpg\",\"width\":1140,\"height\":645},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/aleh-participa-en-el-world-hepatitis-summit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/alehlatam.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALEH participa en el World Hepatitis Summit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"name\":\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"description\":\"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.\",\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"alternateName\":\"ALEH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alehlatam.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\",\"name\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"alternateName\":\"ALEH\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"width\":2000,\"height\":1493,\"caption\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/alehlatam.org\"],\"url\":\"https:\\\/\\\/alehlatam.org\\\/pt\\\/author\\\/admin-eventual\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALEH participa en el World Hepatitis Summit - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alehlatam.org\/pt\/aleh-participa-en-el-world-hepatitis-summit\/","og_locale":"pt_BR","og_type":"article","og_title":"ALEH participa en el World Hepatitis Summit - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","og_description":"El WORLD HEPATITIS SUMMIT, se celebr\u00f3 del 01 al 03 de noviembre en S\u00e3o Paulo, Brasil. El tema del WORLD HEPATITIS SUMMIT 2017 en S\u00e3o Paulo, fue\u00a0Implementing the Global Health Sector Strategy on Viral Hepatitis (GHSS): Towards the elimination of hepatitis as a public health threat. ALEH fue invitado a una discusi\u00f3n paralela con AASLD, [&hellip;]","og_url":"https:\/\/alehlatam.org\/pt\/aleh-participa-en-el-world-hepatitis-summit\/","og_site_name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","article_published_time":"2017-11-04T03:00:00+00:00","og_image":[{"width":1140,"height":645,"url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/aleh-world-hepatitis-summit.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alehlatam.org\/aleh-participa-en-el-world-hepatitis-summit\/#article","isPartOf":{"@id":"https:\/\/alehlatam.org\/aleh-participa-en-el-world-hepatitis-summit\/"},"author":{"name":"admin","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f"},"headline":"ALEH participa en el World Hepatitis Summit","datePublished":"2017-11-04T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/alehlatam.org\/aleh-participa-en-el-world-hepatitis-summit\/"},"wordCount":433,"publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"image":{"@id":"https:\/\/alehlatam.org\/aleh-participa-en-el-world-hepatitis-summit\/#primaryimage"},"thumbnailUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/aleh-world-hepatitis-summit.jpg","articleSection":["Uncategorized"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/alehlatam.org\/aleh-participa-en-el-world-hepatitis-summit\/","url":"https:\/\/alehlatam.org\/aleh-participa-en-el-world-hepatitis-summit\/","name":"ALEH participa en el World Hepatitis Summit - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","isPartOf":{"@id":"https:\/\/alehlatam.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alehlatam.org\/aleh-participa-en-el-world-hepatitis-summit\/#primaryimage"},"image":{"@id":"https:\/\/alehlatam.org\/aleh-participa-en-el-world-hepatitis-summit\/#primaryimage"},"thumbnailUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/aleh-world-hepatitis-summit.jpg","datePublished":"2017-11-04T03:00:00+00:00","breadcrumb":{"@id":"https:\/\/alehlatam.org\/aleh-participa-en-el-world-hepatitis-summit\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alehlatam.org\/aleh-participa-en-el-world-hepatitis-summit\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alehlatam.org\/aleh-participa-en-el-world-hepatitis-summit\/#primaryimage","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/aleh-world-hepatitis-summit.jpg","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/aleh-world-hepatitis-summit.jpg","width":1140,"height":645},{"@type":"BreadcrumbList","@id":"https:\/\/alehlatam.org\/aleh-participa-en-el-world-hepatitis-summit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/alehlatam.org\/"},{"@type":"ListItem","position":2,"name":"ALEH participa en el World Hepatitis Summit"}]},{"@type":"WebSite","@id":"https:\/\/alehlatam.org\/#website","url":"https:\/\/alehlatam.org\/","name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","description":"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.","publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"alternateName":"ALEH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alehlatam.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/alehlatam.org\/#organization","name":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","alternateName":"ALEH","url":"https:\/\/alehlatam.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","width":2000,"height":1493,"caption":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado"},"image":{"@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/alehlatam.org"],"url":"https:\/\/alehlatam.org\/pt\/author\/admin-eventual\/"}]}},"_links":{"self":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts\/14156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/comments?post=14156"}],"version-history":[{"count":0,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts\/14156\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/media\/14154"}],"wp:attachment":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/media?parent=14156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/categories?post=14156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/tags?post=14156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}