{"id":14488,"date":"2022-02-21T00:00:00","date_gmt":"2022-02-21T03:00:00","guid":{"rendered":"https:\/\/alehlatam.org\/wp2024\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/"},"modified":"2024-12-27T15:02:36","modified_gmt":"2024-12-27T18:02:36","slug":"entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh","status":"publish","type":"post","link":"https:\/\/alehlatam.org\/pt\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/","title":{"rendered":"ENTREVISTA A DRA. GRACIELA CASTRO &#8211;           1\u00b0 Vice-Presidenta de ALEH"},"content":{"rendered":"<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-10872\" src=\"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/Dra.-Castro.jpg\" alt=\"\" width=\"203\" height=\"259\" \/>\u00bfC\u00f3mo ha sido su carrera como hepat\u00f3loga y c\u00f3mo lleg\u00f3 a ser parte de la Junta Directiva de ALEH? \u00bfCu\u00e1les han sido sus motivaciones?<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>R: <em>\u201c<\/em><em>Donde quiera que se ame el arte de la Medicina,\u00a0se ama\u00a0tambi\u00e9n a la\u00a0Humanidad\u201d<\/em> (Plat\u00f3n).<\/p>\n<p>Mi carrera como hepat\u00f3loga ha sido muy gratificante. Me ha permitido desenvolverme en distintos \u00e1mbitos como la docencia, la academia, la investigaci\u00f3n y la ciencia, pero sobre todo tener un gran contacto con los pacientes. He vivido tiempos maravilloso teniendo la oportunidad de tratar pacientes con hepatitis C y curarlos por el descubrimiento de los antivirales de acci\u00f3n directa, tambi\u00e9n es satisfactorio acompa\u00f1arlos en una nueva oportunidad de vida en el trasplante hep\u00e1tico y prevenir y mantener la salud hep\u00e1tica en el h\u00edgado graso recomendando un buen estilo de vida. El estudio del H\u00edgado es apasionante.<\/p>\n<p>Siempre he admirado a la ALEH por su gran compromiso para promover y difundir la Hepatolog\u00eda en todos los pa\u00edses de Latinoam\u00e9rica y el mundo, adem\u00e1s por su alto potencial de estrechar los lazos entre las naciones. Siendo yo residente de gastroenterolog\u00eda tuve la oportunidad de presentar trabajos en esta querida asociaci\u00f3n, donde en el a\u00f1o 2014 tuve el honor de trabajar en la asociaci\u00f3n como secretaria con el Dr. M\u00e9ndez, admirando a\u00fan m\u00e1s a esta asociaci\u00f3n. Uno de los mejores congresos que recuerdo fue en Santiago de Chile con el Dr. Brahm y posteriormente en 2019 en Punta Cana presidido por el Dr. Fernando Contreras, una persona con gran conocimiento y calidad humana a la que admiro. Este \u00faltimo congreso lo recuerdo con gran cari\u00f1o ya que ah\u00ed se me dio la gran oportunidad y privilegio de ser la 2\u00aa Vicepresidenta de la asociaci\u00f3n en donde recib\u00ed un gran apoyo de mis colegas y una presentaci\u00f3n inolvidable a cargo del Dr. Panduro.<\/p>\n<p>Es un orgullo formar parte de la Junta Directiva \u00a0y trabajar con grandes l\u00edderes de Latinoam\u00e9rica y el mundo, pero sobre todo contribuir a concientizar en la prevenci\u00f3n de las enfermedades hep\u00e1ticas e impactar en mejorar la salud del h\u00edgado para disminuir la morbimortalidad, ya que las enfermedades hep\u00e1ticas son de las primeras causas de muerte a nivel mundial.<\/p>\n<p>Algunas de mis motivaciones son influir en salud p\u00fablica para mejorar la salud hep\u00e1tica, impulsar a investigadores tanto j\u00f3venes como mayores porque no hay edad para la ciencia, reunir a las mujeres hepat\u00f3logas y la actualizaci\u00f3n m\u00e9dica para que se conozcan las semejanzas y diferencias en las enfermedades hep\u00e1ticas, as\u00ed como las caracter\u00edsticas de las personas de Am\u00e9rica Latina entre las cuales destacan, el trabajo, la calidez, el cari\u00f1o, sentido del humor, solidaridad, hospitalidad, siempre manteniendo esa fuerza caracter\u00edstica que impulsa a continuar con empe\u00f1o y sin desistir para conseguir la meta que se han propuesto. Mostrar que cada pa\u00eds es mucho m\u00e1s que lo que podemos ver desde afuera y que siempre hay algo que nos une.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>M\u00e9xico es uno de los pa\u00edses m\u00e1s grandes de ALEH, \u00bfQu\u00e9 impacto tiene su presencia en la Junta Directiva y c\u00f3mo se puede potenciar la participaci\u00f3n de su pa\u00eds en la Asociaci\u00f3n?<\/strong><\/p>\n<p>R: Como M\u00e9xico es un privilegio y un gran reto pertenecer a la Junta Directiva. Al ser uno de los pa\u00edses mas grandes, puede contribuir a que el conocimiento y la ciencia por el h\u00edgado lleguen a todos los rincones de cada pa\u00eds de Latinoam\u00e9rica promoviendo la educaci\u00f3n m\u00e9dica continua, la investigaci\u00f3n y la difusi\u00f3n de los padecimientos hep\u00e1ticos. Sumando esfuerzos para trabajar con paso firme en beneficio de la salud, buscar\u00e9 vincular a los profesionales de las Asociaciones mexicanas para trabajar en conjunto, enaltecer el sentido de pertenencia de Latinoam\u00e9rica y darlo a conocer, fortalecer la equidad y bienestar humano.<\/p>\n<p>La ALEH tiene grandes beneficios de educaci\u00f3n y crecimiento acad\u00e9mico por lo que es importante darla a conocer para potenciar la participaci\u00f3n de M\u00e9xico, siempre con un fuerte compromiso social de amistad, uni\u00f3n y colaboraci\u00f3n, enalteciendo los valores que nos caracterizan.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfC\u00f3mo esperan en ALEH dar una continuidad a los proyectos de la Asociaci\u00f3n? \u00bfA su visi\u00f3n, misi\u00f3n, objetivos y actividades?<\/strong><\/p>\n<p>R: La continuidad en la ALEH se dar\u00e1 con un plan estrat\u00e9gico iniciado el Dr. Marcelo \u00a0Silva con quien comparto ideales como el sentido de pertenencia, dando continuidad a la gesti\u00f3n y desarrollo, relaciones regionales e internacionales, congresos y cursos anuales de gran calidad, educaci\u00f3n m\u00e9dica continua y desarrollo acad\u00e9mico, aumentar el n\u00famero de asociados y las oportunidades de colaboraci\u00f3n entre los diferentes pa\u00edses, seguir impulsando los grupos de inter\u00e9s, intercambiar los conocimientos, experiencias y avances, logrando una posici\u00f3n s\u00f3lida de liderazgo enalteciendo a Latinoam\u00e9rica con gran compromiso y \u00e9tica y as\u00ed lograr estrechar lazos y seguir creciendo como asociaci\u00f3n. La enorme fuerza de nuestra gente, historia y tradiciones, son prueba de lo grande que es Am\u00e9rica Latina.<\/p>\n<p>Tendr\u00e9 el honor de representar a la ALEH y esto me llena de emoci\u00f3n y orgullo, agradezco a todas las personas que me han acompa\u00f1ado en este camino. Agradezco a la Junta Directiva su gran apoyo.<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u201cNunca vamos a ser capaces de volar tan alto a menos que nos apoyemos los unos a otros\u201d<\/em> (Emma Watson).<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo ha sido su carrera como hepat\u00f3loga y c\u00f3mo lleg\u00f3 a ser parte de la Junta Directiva de ALEH? \u00bfCu\u00e1les han sido sus motivaciones? \u00a0 R: \u201cDonde quiera que se ame el arte de la Medicina,\u00a0se ama\u00a0tambi\u00e9n a la\u00a0Humanidad\u201d (Plat\u00f3n). Mi carrera como hepat\u00f3loga ha sido muy gratificante. Me ha permitido desenvolverme en distintos \u00e1mbitos [&hellip;]<\/p>","protected":false},"author":1,"featured_media":14476,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ENTREVISTA A DRA. GRACIELA CASTRO -      1\u00b0 Vice-Presidenta de ALEH - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alehlatam.org\/pt\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA A DRA. GRACIELA CASTRO -      1\u00b0 Vice-Presidenta de ALEH - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"og:description\" content=\"\u00bfC\u00f3mo ha sido su carrera como hepat\u00f3loga y c\u00f3mo lleg\u00f3 a ser parte de la Junta Directiva de ALEH? \u00bfCu\u00e1les han sido sus motivaciones? \u00a0 R: \u201cDonde quiera que se ame el arte de la Medicina,\u00a0se ama\u00a0tambi\u00e9n a la\u00a0Humanidad\u201d (Plat\u00f3n). Mi carrera como hepat\u00f3loga ha sido muy gratificante. Me ha permitido desenvolverme en distintos \u00e1mbitos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alehlatam.org\/pt\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/\" \/>\n<meta property=\"og:site_name\" content=\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-21T03:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-27T18:02:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/Dra.-Castro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"142\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\"},\"headline\":\"ENTREVISTA A DRA. GRACIELA CASTRO &#8211; 1\u00b0 Vice-Presidenta de ALEH\",\"datePublished\":\"2022-02-21T03:00:00+00:00\",\"dateModified\":\"2024-12-27T18:02:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\\\/\"},\"wordCount\":949,\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Dra.-Castro.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\\\/\",\"name\":\"ENTREVISTA A DRA. GRACIELA CASTRO - 1\u00b0 Vice-Presidenta de ALEH - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Dra.-Castro.jpg\",\"datePublished\":\"2022-02-21T03:00:00+00:00\",\"dateModified\":\"2024-12-27T18:02:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alehlatam.org\\\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Dra.-Castro.jpg\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Dra.-Castro.jpg\",\"width\":142,\"height\":181},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/alehlatam.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA A DRA. GRACIELA CASTRO &#8211; 1\u00b0 Vice-Presidenta de ALEH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#website\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"name\":\"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"description\":\"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.\",\"publisher\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\"},\"alternateName\":\"ALEH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alehlatam.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#organization\",\"name\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\",\"alternateName\":\"ALEH\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"contentUrl\":\"https:\\\/\\\/alehlatam.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-ALEH-Transparente.png\",\"width\":2000,\"height\":1493,\"caption\":\"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado\"},\"image\":{\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alehlatam.org\\\/#\\\/schema\\\/person\\\/fa1d1ad185655050f43740e6c82be26f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/alehlatam.org\"],\"url\":\"https:\\\/\\\/alehlatam.org\\\/pt\\\/author\\\/admin-eventual\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ENTREVISTA A DRA. GRACIELA CASTRO -      1\u00b0 Vice-Presidenta de ALEH - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alehlatam.org\/pt\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA A DRA. GRACIELA CASTRO -      1\u00b0 Vice-Presidenta de ALEH - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","og_description":"\u00bfC\u00f3mo ha sido su carrera como hepat\u00f3loga y c\u00f3mo lleg\u00f3 a ser parte de la Junta Directiva de ALEH? \u00bfCu\u00e1les han sido sus motivaciones? \u00a0 R: \u201cDonde quiera que se ame el arte de la Medicina,\u00a0se ama\u00a0tambi\u00e9n a la\u00a0Humanidad\u201d (Plat\u00f3n). Mi carrera como hepat\u00f3loga ha sido muy gratificante. Me ha permitido desenvolverme en distintos \u00e1mbitos [&hellip;]","og_url":"https:\/\/alehlatam.org\/pt\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/","og_site_name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","article_published_time":"2022-02-21T03:00:00+00:00","article_modified_time":"2024-12-27T18:02:36+00:00","og_image":[{"width":142,"height":181,"url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/Dra.-Castro.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alehlatam.org\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/#article","isPartOf":{"@id":"https:\/\/alehlatam.org\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/"},"author":{"name":"admin","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f"},"headline":"ENTREVISTA A DRA. GRACIELA CASTRO &#8211; 1\u00b0 Vice-Presidenta de ALEH","datePublished":"2022-02-21T03:00:00+00:00","dateModified":"2024-12-27T18:02:36+00:00","mainEntityOfPage":{"@id":"https:\/\/alehlatam.org\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/"},"wordCount":949,"publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"image":{"@id":"https:\/\/alehlatam.org\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/#primaryimage"},"thumbnailUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/Dra.-Castro.jpg","articleSection":["Uncategorized"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/alehlatam.org\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/","url":"https:\/\/alehlatam.org\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/","name":"ENTREVISTA A DRA. GRACIELA CASTRO - 1\u00b0 Vice-Presidenta de ALEH - ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","isPartOf":{"@id":"https:\/\/alehlatam.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alehlatam.org\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/#primaryimage"},"image":{"@id":"https:\/\/alehlatam.org\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/#primaryimage"},"thumbnailUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/Dra.-Castro.jpg","datePublished":"2022-02-21T03:00:00+00:00","dateModified":"2024-12-27T18:02:36+00:00","breadcrumb":{"@id":"https:\/\/alehlatam.org\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alehlatam.org\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alehlatam.org\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/#primaryimage","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/Dra.-Castro.jpg","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/03\/Dra.-Castro.jpg","width":142,"height":181},{"@type":"BreadcrumbList","@id":"https:\/\/alehlatam.org\/entrevista-a-dra-graciela-castro-1-vice-presidenta-de-aleh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/alehlatam.org\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA A DRA. GRACIELA CASTRO &#8211; 1\u00b0 Vice-Presidenta de ALEH"}]},{"@type":"WebSite","@id":"https:\/\/alehlatam.org\/#website","url":"https:\/\/alehlatam.org\/","name":"ALEH - Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","description":"Conectamos a la comunidad de hepatolog\u00eda en Latinoam\u00e9rica. ALEH impulsa la investigaci\u00f3n y el intercambio cient\u00edfico para mejorar la salud hep\u00e1tica regional.","publisher":{"@id":"https:\/\/alehlatam.org\/#organization"},"alternateName":"ALEH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alehlatam.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/alehlatam.org\/#organization","name":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado","alternateName":"ALEH","url":"https:\/\/alehlatam.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/","url":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","contentUrl":"https:\/\/alehlatam.org\/wp-content\/uploads\/2024\/01\/Logo-ALEH-Transparente.png","width":2000,"height":1493,"caption":"Asociaci\u00f3n Latinoamericana para el Estudio del H\u00edgado"},"image":{"@id":"https:\/\/alehlatam.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/alehlatam.org\/#\/schema\/person\/fa1d1ad185655050f43740e6c82be26f","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/066ceb3878c0b46b8dc6198e9068d17ac44feeadfaad1557708d35cd0f130189?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/alehlatam.org"],"url":"https:\/\/alehlatam.org\/pt\/author\/admin-eventual\/"}]}},"_links":{"self":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts\/14488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/comments?post=14488"}],"version-history":[{"count":0,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/posts\/14488\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/media\/14476"}],"wp:attachment":[{"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/media?parent=14488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/categories?post=14488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alehlatam.org\/pt\/wp-json\/wp\/v2\/tags?post=14488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}